{"id":8,"date":"2019-05-21T03:12:49","date_gmt":"2019-05-21T03:12:49","guid":{"rendered":"http:\/\/www.ishopdea.com\/wishlist\/"},"modified":"2019-05-22T11:25:53","modified_gmt":"2019-05-22T03:25:53","slug":"wishlist","status":"publish","type":"page","link":"https:\/\/www.ishopdea.com\/zh\/wishlist\/","title":{"rendered":"Wishlist"},"content":{"rendered":"<div class=\"woocommerce soo-wishlist\">\n\n<div class=\"wishlist-empty\">\n\t<p>Your wishlist is currently empty.<\/p>\n<\/div>\n\n\n<\/div>","protected":false},"excerpt":{"rendered":"Your wishlist is&hellip;","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-8","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Wishlist - ishopdea<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ishopdea.com\/zh\/wishlist\/\" \/>\n<meta property=\"og:locale\" content=\"zh_HK\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Wishlist - ishopdea\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ishopdea.com\/zh\/wishlist\/\" \/>\n<meta property=\"og:site_name\" content=\"ishopdea\" \/>\n<meta property=\"article:modified_time\" content=\"2019-05-22T03:25:53+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"http:\/\/www.ishopdea.com\/en\/wishlist\/\",\"url\":\"http:\/\/www.ishopdea.com\/en\/wishlist\/\",\"name\":\"Wishlist - ishopdea\",\"isPartOf\":{\"@id\":\"https:\/\/www.ishopdea.com\/#website\"},\"datePublished\":\"2019-05-21T03:12:49+00:00\",\"dateModified\":\"2019-05-22T03:25:53+00:00\",\"breadcrumb\":{\"@id\":\"http:\/\/www.ishopdea.com\/en\/wishlist\/#breadcrumb\"},\"inLanguage\":\"zh-HK\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/www.ishopdea.com\/en\/wishlist\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/www.ishopdea.com\/en\/wishlist\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.ishopdea.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Wishlist\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.ishopdea.com\/#website\",\"url\":\"https:\/\/www.ishopdea.com\/\",\"name\":\"ishopdea\",\"description\":\"Lifestyle Eco Store\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.ishopdea.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"zh-HK\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Wishlist - ishopdea","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ishopdea.com\/zh\/wishlist\/","og_locale":"zh_HK","og_type":"article","og_title":"Wishlist - ishopdea","og_url":"https:\/\/www.ishopdea.com\/zh\/wishlist\/","og_site_name":"ishopdea","article_modified_time":"2019-05-22T03:25:53+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"http:\/\/www.ishopdea.com\/en\/wishlist\/","url":"http:\/\/www.ishopdea.com\/en\/wishlist\/","name":"Wishlist - ishopdea","isPartOf":{"@id":"https:\/\/www.ishopdea.com\/#website"},"datePublished":"2019-05-21T03:12:49+00:00","dateModified":"2019-05-22T03:25:53+00:00","breadcrumb":{"@id":"http:\/\/www.ishopdea.com\/en\/wishlist\/#breadcrumb"},"inLanguage":"zh-HK","potentialAction":[{"@type":"ReadAction","target":["http:\/\/www.ishopdea.com\/en\/wishlist\/"]}]},{"@type":"BreadcrumbList","@id":"http:\/\/www.ishopdea.com\/en\/wishlist\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.ishopdea.com\/"},{"@type":"ListItem","position":2,"name":"Wishlist"}]},{"@type":"WebSite","@id":"https:\/\/www.ishopdea.com\/#website","url":"https:\/\/www.ishopdea.com\/","name":"ishopdea","description":"Lifestyle Eco Store","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ishopdea.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"zh-HK"}]}},"_links":{"self":[{"href":"https:\/\/www.ishopdea.com\/zh\/wp-json\/wp\/v2\/pages\/8","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ishopdea.com\/zh\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.ishopdea.com\/zh\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.ishopdea.com\/zh\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ishopdea.com\/zh\/wp-json\/wp\/v2\/comments?post=8"}],"version-history":[{"count":0,"href":"https:\/\/www.ishopdea.com\/zh\/wp-json\/wp\/v2\/pages\/8\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.ishopdea.com\/zh\/wp-json\/wp\/v2\/media?parent=8"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}